{"id":18645,"date":"2022-05-17T12:26:54","date_gmt":"2022-05-17T04:26:54","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=18645"},"modified":"2024-09-26T16:13:02","modified_gmt":"2024-09-26T08:13:02","slug":"%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/","title":{"rendered":"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM-724x1024.jpeg\" alt=\"\" class=\"wp-image-18646\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM-724x1024.jpeg 724w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM-212x300.jpeg 212w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM-768x1086.jpeg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM-1086x1536.jpeg 1086w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg 1131w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p>\ud83d\udccd\u6642\u9593\uff1a2022\u5e746\u670810\u65e5\uff0c\u665a\u4e0a7:30-8:30<br>\ud83d\udccd\u5c0d\u8c61:\u807e\u4eba\u6216\u807d\u969c\u4eba\u58eb\uff08\u540d\u984d8\u540d\uff09<br>\ud83d\udccd\u8cbb\u7528\uff1aMOP20<br>\ud83d\udccd\u5099\u8a3b\uff1a<br>1\ufe0f\u20e3\u9700\u81ea\u5099\u745c\u4f3d\u588a\u53ca\u745c\u4f3d\u78da\u3002<br>2\ufe0f\u20e3\u5982\u9700\u5354\u52a9\u8cfc\u8cb7\u6750\u6599\uff0c\u53ef\u5411\u5de5\u4f5c\u4eba\u54e1\u67e5\u8a62\u3002<br>3\ufe0f\u20e3\u9aa8\u8cea\u758f\u9b06\u53ca\u8fd1\u671f\u505a\u5b8c\u624b\u8853\u4e0d\u5b9c\u53c3\u52a0\u3002<\/p>\n\n\n\n<p>\ud83d\udcad\u5831\u540d\u53ca\u67e5\u8a62\uff1a\u53ef\u77ed\u8a0a\u81f366516093\u3001\u4e2d\u5fc3\u5fae\u4fe1DCENTER2015\u3001\u96fb\u8a7128261658\u6216\u89aa\u81e8\u4e2d\u5fc3\u806f\u7d61\u6797\u59d1\u5a18<\/p>\n\n\n\n<p>#\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3 #\u745c\u4f3d #\u807e\u4eba #\u807d\u969c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udccd\u6642\u9593\uff1a2022\u5e746\u670810\u65e5\uff0c\u665a\u4e0a7:30-8:30\ud83d\udccd\u5c0d\u8c61:\u807e\u4eba\u6216\u807d\u969c\u4eba\u58eb\uff08\u540d\u984d8\u540d\uff09\ud83d\udccd\u8cbb\u7528\uff1aMOP20\ud83d\udccd\u5099\u8a3b [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":18646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112,191,113],"tags":[],"class_list":["post-18645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-related-activities","category-news-all","category-activity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\ud83e\uddd8\ud83c\udffb\u2640\ufe0f-\u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f-\ud83e\uddd8\ud83c\udffb-\u53c8\u4f86\u4e86\uff0c\u73fe\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udccd\u6642\u9593\uff1a2022\u5e746\u670810\u65e5\uff0c\u665a\u4e0a7:30-8:30\ud83d\udccd\u5c0d\u8c61:\u807e\u4eba\u6216\u807d\u969c\u4eba\u58eb\uff08\u540d\u984d8\u540d\uff09\ud83d\udccd\u8cbb\u7528\uff1aMOP20\ud83d\udccd\u5099\u8a3b [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\ud83e\uddd8\ud83c\udffb\u2640\ufe0f-\u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f-\ud83e\uddd8\ud83c\udffb-\u53c8\u4f86\u4e86\uff0c\u73fe\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-17T04:26:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T08:13:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757\",\"datePublished\":\"2022-05-17T04:26:54+00:00\",\"dateModified\":\"2024-09-26T08:13:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg\",\"articleSection\":[\"\u6240\u6709\u6d3b\u52d5\",\"\u6240\u6709\u6d88\u606f\",\"\u6d3b\u52d5\"],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/\",\"name\":\"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg\",\"datePublished\":\"2022-05-17T04:26:54+00:00\",\"dateModified\":\"2024-09-26T08:13:02+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg\",\"width\":1131,\"height\":1600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\ud83e\uddd8\ud83c\udffb\u2640\ufe0f-\u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f-\ud83e\uddd8\ud83c\udffb-\u53c8\u4f86\u4e86\uff0c\u73fe\/","og_locale":"zh_TW","og_type":"article","og_title":"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\ud83d\udccd\u6642\u9593\uff1a2022\u5e746\u670810\u65e5\uff0c\u665a\u4e0a7:30-8:30\ud83d\udccd\u5c0d\u8c61:\u807e\u4eba\u6216\u807d\u969c\u4eba\u58eb\uff08\u540d\u984d8\u540d\uff09\ud83d\udccd\u8cbb\u7528\uff1aMOP20\ud83d\udccd\u5099\u8a3b [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\ud83e\uddd8\ud83c\udffb\u2640\ufe0f-\u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f-\ud83e\uddd8\ud83c\udffb-\u53c8\u4f86\u4e86\uff0c\u73fe\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2022-05-17T04:26:54+00:00","article_modified_time":"2024-09-26T08:13:02+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757","datePublished":"2022-05-17T04:26:54+00:00","dateModified":"2024-09-26T08:13:02+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/"},"wordCount":3,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg","articleSection":["\u6240\u6709\u6d3b\u52d5","\u6240\u6709\u6d88\u606f","\u6d3b\u52d5"],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/","url":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/","name":"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f \u745c\u4f3d\u9ad4\u9a57\u65e5\u7b2c\u4e09\u671f \ud83e\uddd8\ud83c\udffb \u53c8\u4f86\u4e86\uff0c\u73fe\u6b63\u958b\u653e\u5831\u540d\u5566\u2757\u2757 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg","datePublished":"2022-05-17T04:26:54+00:00","dateModified":"2024-09-26T08:13:02+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%a7%98%f0%9f%8f%bb%e2%99%80%ef%b8%8f-%e7%91%9c%e4%bc%bd%e9%ab%94%e9%a9%97%e6%97%a5%e7%ac%ac%e4%b8%89%e6%9c%9f-%f0%9f%a7%98%f0%9f%8f%bb-%e5%8f%88%e4%be%86%e4%ba%86%ef%bc%8c%e7%8f%be\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-17-at-10.59.24-AM.jpeg","width":1131,"height":1600},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/18645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=18645"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/18645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/18646"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=18645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=18645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=18645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}