{"id":20784,"date":"2022-09-29T19:24:47","date_gmt":"2022-09-29T11:24:47","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=20784"},"modified":"2024-09-26T16:11:55","modified_gmt":"2024-09-26T08:11:55","slug":"%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/","title":{"rendered":"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55  \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-724x1024.png\" alt=\"\" class=\"wp-image-20785\"\/><figcaption><em>\u4eca\u5e749\u6708\u672c\u6703\u7372\u5f97\u71b1\u5fc3\u4eba\u58eb\u8cc7\u52a9\u90e8\u4efd\u8cbb\u7528\uff0c\u958b\u5c55\u79d1\u5229\u8033\uff08Cochlear\uff09N6\u6a5f\u578b\u4eba\u5de5\u8033\u8778\u4f7f\u7528\u8005\u7684\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9<\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>\ud83d\udd38\u4e00\u76f4\u4ee5\u4f86\u4eba\u5de5\u8033\u8778\u7684\u690d\u5165\u548c\u8ddf\u9032\u4e3b\u8981\u5728\u5916\u5730\u9032\u884c\uff0c\u4f46\u8fd1\u5e74\u7531\u65bc\u9632\u75ab\u76f8\u95dc\u653f\u7b56\u5f71\u97ff\uff0c\u51fa\u5165\u5883\u8b8a\u5f97\u56f0\u96e3\u91cd\u91cd\uff0c\u5c0e\u81f4\u90e8\u5206\u4eba\u5de5\u8033\u8778\u4f7f\u7528\u8005\u672a\u80fd\u53ca\u6642\u8ddf\u9032\u8abf\u6a5f\uff0c\u4f7f\u8f14\u5177\u7121\u6cd5\u5145\u5206\u767c\u63ee\u4f5c\u7528\u800c\u5f71\u97ff\u5b78\u7fd2\u53ca\u767c\u5c55\u3002<\/strong><\/p>\n\n\n\n<p><strong>\ud83d\udd38\u81ea2021\u5e74\u8d77\uff0c\u672c\u6703\u6301\u7e8c\u5411\u653f\u5e9c\u53cd\u6620\u76f8\u95dc\u8a34\u6c42\uff0c\u7121\u5948\u76f4\u81f32022\u5e749\u6708\u4ecd\u672a\u7372\u653f\u5e9c\u7a4d\u6975\u56de\u61c9\u3002<\/strong><\/p>\n\n\n\n<p><strong>\ud83c\udf1f\u6fb3\u9580\u4eba\u71b1\u5fc3\u516c\u76ca\uff0c\u4eca\u5e749\u6708\u672c\u6703\u7372\u5f97\u71b1\u5fc3\u4eba\u58eb\u8cc7\u52a9\u90e8\u4efd\u8cbb\u7528\uff0c\u958b\u5c55\u79d1\u5229\u8033\uff08Cochlear\uff09N6\u6a5f\u578b\u4eba\u5de5\u8033\u8778\u4f7f\u7528\u8005\u7684\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u3002<\/strong><br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f02-724x1024.png\" alt=\"\" class=\"wp-image-20786\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f02-724x1024.png 724w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f02-212x300.png 212w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f02-768x1086.png 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f02-1086x1536.png 1086w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f02.png 1414w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p class=\"has-text-color has-medium-font-size\" style=\"color:#0374b6\"><strong>\ud83d\udccd\u5730\u9ede\uff1a\u555f\u8070\u4e2d\u5fc3<br>\ud83d\udccd\u5c0d\u8c61\uff1a\u79d1\u5229\u8033\uff08Cochlear\uff09N6\u6a5f\u578b\u690d\u5165\u8005<br>\ud83d\udccd\u8cc7\u52a9\u540d\u984d\uff1a\u7d04 25 \u540d<br>\ud83d\udccd\u8cbb\u7528\uff1a\u539f\u50f9 1,200\u6fb3\u9580\u5143\uff0c\u53d7\u8cc7\u52a9\u8005\u53ea\u9700\u81ea\u8cbb 200 \u6fb3\u9580\u5143<br>\ud83d\udccd\u8cc7\u52a9\u6b21\u6578\uff1a\u6bcf\u540d\u53d7\u8cc7\u52a9\u8005\u53ef\u73721\u6b21\u670d\u52d9\u6b21\u6578<br>\ud83d\udccd\u9810\u8a08\u5be6\u884c\u65e5\u671f\uff1a2022 \u5e74 10 \u6708\u4e2d<br>\ud83d\udccd\u670d\u52d9\u5167\u5bb9\uff1a\u7531\u7d93\u5c08\u696d\u57f9\u8a13\u4e4b\u807d\u529b\u5e2b\u63d0\u4f9b\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\uff1b<\/strong><br>\u3000\u3000\u3000\u3000\u3000\u3000<strong>\u76ee\u524d\u652f\u6301\u79d1\u5229\u8033\uff08Cochlear\uff09N6\u6a5f\u578b<\/strong>\u3000<br><br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-color\" style=\"color:#00921b;font-size:25px\"><strong>\ud83c\udf1f\u67e5\u8a62\u6216\u9810\u7d04\uff1a\u8acb\u81f4\u96fb 28415554 \u3001\u77ed\u8a0a 62655615\u3001\u555f\u8070\u4e2d\u5fc3\u5fae\u4fe1\u6216\u5411\u555f\u8070\u4e2d\u5fc3\u807d\u529b\u5e2b\u9810\u7d04<\/strong><br><br><\/p>\n\n\n\n<p>#\u6fb3\u9580\u807e\u4eba\u5354\u6703 #\u555f\u8070\u4e2d\u5fc3<\/p>\n\n\n\n<p>#\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9<\/p>\n\n\n\n<p>#\u79d1\u5229\u8033CochlearN6\u6a5f\u578b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38\u4e00\u76f4\u4ee5\u4f86\u4eba\u5de5\u8033\u8778\u7684\u690d\u5165\u548c\u8ddf\u9032\u4e3b\u8981\u5728\u5916\u5730\u9032\u884c\uff0c\u4f46\u8fd1\u5e74\u7531\u65bc\u9632\u75ab\u76f8\u95dc\u653f\u7b56\u5f71\u97ff\uff0c\u51fa\u5165\u5883\u8b8a\u5f97\u56f0\u96e3\u91cd\u91cd\uff0c\u5c0e\u81f4\u90e8\u5206\u4eba\u5de5\u8033\u8778 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":20785,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,127,191,113],"tags":[],"class_list":["post-20784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association-news","category-association-news-kc","category-news-all","category-activity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55-\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38\u4e00\u76f4\u4ee5\u4f86\u4eba\u5de5\u8033\u8778\u7684\u690d\u5165\u548c\u8ddf\u9032\u4e3b\u8981\u5728\u5916\u5730\u9032\u884c\uff0c\u4f46\u8fd1\u5e74\u7531\u65bc\u9632\u75ab\u76f8\u95dc\u653f\u7b56\u5f71\u97ff\uff0c\u51fa\u5165\u5883\u8b8a\u5f97\u56f0\u96e3\u91cd\u91cd\uff0c\u5c0e\u81f4\u90e8\u5206\u4eba\u5de5\u8033\u8778 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55-\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-29T11:24:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T08:11:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1405\" \/>\n\t<meta property=\"og:image:height\" content=\"1520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\",\"datePublished\":\"2022-09-29T11:24:47+00:00\",\"dateModified\":\"2024-09-26T08:11:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/\"},\"wordCount\":9,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png\",\"articleSection\":[\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u555f\u8070\u4e2d\u5fc3)\",\"\u6240\u6709\u6d88\u606f\",\"\u6d3b\u52d5\"],\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/\",\"name\":\"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png\",\"datePublished\":\"2022-09-29T11:24:47+00:00\",\"dateModified\":\"2024-09-26T08:11:55+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png\",\"width\":1405,\"height\":1520},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55-\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\/","og_locale":"zh_TW","og_type":"article","og_title":"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\ud83d\udd38\u4e00\u76f4\u4ee5\u4f86\u4eba\u5de5\u8033\u8778\u7684\u690d\u5165\u548c\u8ddf\u9032\u4e3b\u8981\u5728\u5916\u5730\u9032\u884c\uff0c\u4f46\u8fd1\u5e74\u7531\u65bc\u9632\u75ab\u76f8\u95dc\u653f\u7b56\u5f71\u97ff\uff0c\u51fa\u5165\u5883\u8b8a\u5f97\u56f0\u96e3\u91cd\u91cd\uff0c\u5c0e\u81f4\u90e8\u5206\u4eba\u5de5\u8033\u8778 [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55-\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2022-09-29T11:24:47+00:00","article_modified_time":"2024-09-26T08:11:55+00:00","og_image":[{"width":1405,"height":1520,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9","datePublished":"2022-09-29T11:24:47+00:00","dateModified":"2024-09-26T08:11:55+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/"},"wordCount":9,"commentCount":0,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png","articleSection":["\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u555f\u8070\u4e2d\u5fc3)","\u6240\u6709\u6d88\u606f","\u6d3b\u52d5"],"inLanguage":"zh-TW","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/","url":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/","name":"\u555f\u8070\u4e2d\u5fc3\u5c07\u958b\u5c55 \u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png","datePublished":"2022-09-29T11:24:47+00:00","dateModified":"2024-09-26T08:11:55+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e5%95%9f%e8%81%b0%e4%b8%ad%e5%bf%83%e5%b0%87%e9%96%8b%e5%b1%95-%e4%ba%ba%e5%b7%a5%e8%80%b3%e8%9d%b8%e8%aa%bf%e6%a9%9f%e6%9c%8d%e5%8b%99\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2022\/09\/\u4eba\u5de5\u8033\u8778\u8abf\u6a5f\u670d\u52d9\u6d77\u5831\uff3f01-e1664450628962.png","width":1405,"height":1520},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/20784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=20784"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/20784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/20785"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=20784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=20784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=20784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}