{"id":22406,"date":"2023-11-16T17:53:19","date_gmt":"2023-11-16T09:53:19","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=22406"},"modified":"2024-09-26T16:10:02","modified_gmt":"2024-09-26T08:10:02","slug":"%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/","title":{"rendered":"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg\" alt=\"\" class=\"wp-image-22407\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg 1080w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM-800x800.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM-150x150.jpeg 150w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM-768x768.jpeg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p><br>\u2665\ufe0f #\u85dd\u589f\u9650\u5b9a3.0 \u300c\u652f\u6301\u807e\u5354\u6587\u5275\u300d<br>\u85dd\u589f\u671f\u9593\uff0c\u652f\u6301\u300c\u807e\u5354\u6587\u5275\u300d\u4efb\u4f55\u7fa9\u8ce3\u54c1\u6eff$200\uff0c\u53ef\u7372$20\u73fe\u91d1\u62b5\u7528\u5238\u4e59\u5f35\uff0c\u65bc\u300cMDA Charity Shop\u300d\u7dda\u4e0a\u7fa9\u8ce3\u5e73\u53f0\u4f7f\u7528!<\/p>\n\n\n\n<p>\u300a #\u5854\u77f3\u6709\u624b\u8a9e \u300b\u5de5\u4f5c\u574a\ud83d\udc50\ud83c\udffb<br>\u9996\u65e5\u9996\u5834\u5de5\u4f5c\u574a\u4fc218:30\u958b\u59cb\uff0c\u653e\u5b78\u6216\u8005\u6536\u5de5\u904e\u9ece\u525b\u525b\u4f86\u5f97\u53ca\uff0c\u7d04\u5b9a\u60a8\u5854\u77f3\u898b\ud83d\udc81\ud83c\udffb\u200d\u2640\ufe0f<br>\u23e911 \/ 16\u300117 \u258f18:30\u300120:30<br>\u23e911 \/ 18\u300119 \u258f16:30\u300119:30<\/p>\n\n\n\n<p>\u807e\u5354\u6587\u5275<em>\ud83e\udef6\ud83c\udffb #\u5854\u77f3\u6709\u624b\u8a9e\u5de5\u4f5c\u574a<\/em>\ud83d\udc50\ud83c\udffb<\/p>\n\n\n\n<p>\ud83d\udccd\u6524\u4f4d \u258f#\u6fb3\u9580\u807e\u4eba\u5354\u6703<br>\ud83d\udccd\u7de8\u865f \u258f#MO62<br>\ud83d\udccd\u65e5\u671f \u258f2023\u5e7411\u670816-19\u65e5<br>\u56db\u3001\u4e94 17:00 &#8211; 22:00<br>\u516d\u3001\u65e5 15:00 &#8211; 22:00<\/p>\n\n\n\n<p>\u6fb3\u9580\u807e\u4eba\u5354\u6703 #2023\u79cb\u5b63\u5854\u77f3\u85dd\u589f #\u624b\u8a9e\u50b3\u60c5 #\u5fc3\u52d5\u7121\u8072 #\u807e\u5354\u6587\u5275 #\u5171\u7bc9\u878d\u548c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2665\ufe0f #\u85dd\u589f\u9650\u5b9a3.0 \u300c\u652f\u6301\u807e\u5354\u6587\u5275\u300d\u85dd\u589f\u671f\u9593\uff0c\u652f\u6301\u300c\u807e\u5354\u6587\u5275\u300d\u4efb\u4f55\u7fa9\u8ce3\u54c1\u6eff$200\uff0c\u53ef\u7372$20\u73fe\u91d1\u62b5\u7528\u5238\u4e59 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":22407,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112,191,113],"tags":[],"class_list":["post-22406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-related-activities","category-news-all","category-activity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\ud83d\udce2\u3010-2-0-2-3-\u79cb-\u5b63-\u5854-\u77f3-\u85dd-\u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\u2665\ufe0f #\u85dd\u589f\u9650\u5b9a3.0 \u300c\u652f\u6301\u807e\u5354\u6587\u5275\u300d\u85dd\u589f\u671f\u9593\uff0c\u652f\u6301\u300c\u807e\u5354\u6587\u5275\u300d\u4efb\u4f55\u7fa9\u8ce3\u54c1\u6eff$200\uff0c\u53ef\u7372$20\u73fe\u91d1\u62b5\u7528\u5238\u4e59 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\ud83d\udce2\u3010-2-0-2-3-\u79cb-\u5b63-\u5854-\u77f3-\u85dd-\u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T09:53:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T08:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb\",\"datePublished\":\"2023-11-16T09:53:19+00:00\",\"dateModified\":\"2024-09-26T08:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/\"},\"wordCount\":7,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg\",\"articleSection\":[\"\u6240\u6709\u6d3b\u52d5\",\"\u6240\u6709\u6d88\u606f\",\"\u6d3b\u52d5\"],\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/\",\"name\":\"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg\",\"datePublished\":\"2023-11-16T09:53:19+00:00\",\"dateModified\":\"2024-09-26T08:10:02+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg\",\"width\":1080,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\ud83d\udce2\u3010-2-0-2-3-\u79cb-\u5b63-\u5854-\u77f3-\u85dd-\u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb\/","og_locale":"zh_TW","og_type":"article","og_title":"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\u2665\ufe0f #\u85dd\u589f\u9650\u5b9a3.0 \u300c\u652f\u6301\u807e\u5354\u6587\u5275\u300d\u85dd\u589f\u671f\u9593\uff0c\u652f\u6301\u300c\u807e\u5354\u6587\u5275\u300d\u4efb\u4f55\u7fa9\u8ce3\u54c1\u6eff$200\uff0c\u53ef\u7372$20\u73fe\u91d1\u62b5\u7528\u5238\u4e59 [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\ud83d\udce2\u3010-2-0-2-3-\u79cb-\u5b63-\u5854-\u77f3-\u85dd-\u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2023-11-16T09:53:19+00:00","article_modified_time":"2024-09-26T08:10:02+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb","datePublished":"2023-11-16T09:53:19+00:00","dateModified":"2024-09-26T08:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/"},"wordCount":7,"commentCount":0,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg","articleSection":["\u6240\u6709\u6d3b\u52d5","\u6240\u6709\u6d88\u606f","\u6d3b\u52d5"],"inLanguage":"zh-TW","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/","url":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/","name":"\ud83d\udce2\u3010 2 0 2 3 \u79cb \u5b63 \u5854 \u77f3 \u85dd \u589f\u3011\u958b\u59cb\u5566\ud83e\udd1f\ud83c\udffb - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg","datePublished":"2023-11-16T09:53:19+00:00","dateModified":"2024-09-26T08:10:02+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%93%a2%e3%80%90-2-0-2-3-%e7%a7%8b-%e5%ad%a3-%e5%a1%94-%e7%9f%b3-%e8%97%9d-%e5%a2%9f%e3%80%91%e9%96%8b%e5%a7%8b%e5%95%a6%f0%9f%a4%9f%f0%9f%8f%bb\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-16-at-4.01.53-PM.jpeg","width":1080,"height":1080},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/22406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=22406"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/22406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/22407"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=22406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=22406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=22406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}