{"id":22429,"date":"2023-11-21T11:53:05","date_gmt":"2023-11-21T03:53:05","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=22429"},"modified":"2024-09-26T16:10:02","modified_gmt":"2024-09-26T08:10:02","slug":"%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/","title":{"rendered":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1131\" height=\"1600\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-12.39.25.jpeg\" alt=\"\" class=\"wp-image-22432\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-12.39.25.jpeg 1131w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-12.39.25-566x800.jpeg 566w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-12.39.25-768x1086.jpeg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-12.39.25-1086x1536.jpeg 1086w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><\/figure>\n\n\n\n<p>\ud83c\udf84\ud83d\udd14 \u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\u4eca\u5e74\u6d3b\u52d5\u5c07\u70ba\u5927\u5bb6\u5e36\u4f86\u7cbe\u5f69\u7684\u624b\u8a9e\u77ed\u5287\ud83c\udf85\u3001\u6709\u8da3\u6b61\u6a02\u7684\u805a\u6703\u904a\u6232\ud83c\udfae\u3001\u8c50\u5bcc\u7684\u7f8e\u98df\u4f73\u991a\ud83e\udd58\u53ca\u5927\u5bb6\u671f\u5f85\u611f\u6eff\u6eff\u7684\u62bd\u734e\u74b0\u7bc0\ud83c\udf81\uff01\u671f\u5f85\u60a8\u7684\u53c3\u8207\uff0c\u8b93\u6211\u5011\u4e00\u8d77\u5171\u5ea6\u6eab\u99a8\u4e14\u96e3\u5fd8\u7684\u8056\u8a95\u6642\u5149\uff01\ud83d\udc6a\ud83d\udc95<\/p>\n\n\n\n<p>\u25aa\ufe0f\u65e5\u671f\uff1a2023\u5e7412\u67089\u65e5(\u661f\u671f\u516d)<br>\u25aa\ufe0f\u6642\u9593\uff1a12:00 \u2013 15:00 (11:30\u958b\u59cb\u5165\u5834)<br>\u25aa\ufe0f\u5730\u9ede\uff1a\u6fb3\u9580\u96c5\u8fb0\u9152\u5e97-\u91d1\u9e97\u8ed2(\u81ea\u884c\u524d\u5f80)<br>\u25aa\ufe0f\u5c0d\u8c61\uff1a\u807e\/\u807d\u969c\/\u8a9e\u969c\u670d\u52d9\u5c0d\u8c61\u53ca\u5176\u5bb6\u5c6c<br>\u25aa\ufe0f\u5167\u5bb9\uff1a\u81ea\u52a9\u9910\u3001\u904a\u6232\u53ca\u5927\u62bd\u734e<br>\u25aa\ufe0f\u8cbb\u7528\uff1a\u8a73\u898b\u6d77\u5831<\/p>\n\n\n\n<p>\u5831\u540d\u9808\u77e5<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u5831\u540d\u75312023\u5e7411\u670822\u65e5(\u4e09)\u4e0b\u53482:30\u8d77\u81f312\u67086\u65e5\u6b62\u3002<\/li>\n\n\n\n<li>\u5831\u540d\u9700\u5e36\u540c\u8eab\u4efd\u8b49\u89aa\u81e8\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3\u7e73\u8cbb\uff0c\u7e73\u8cbb\u5f8c\u4e0d\u8a2d\u9000\u6b3e\u3002<\/li>\n\n\n\n<li><\/li>\n<\/ul>\n\n\n\n<p>#\u6fb3\u9580\u807e\u4eba\u5354\u6703 #\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3 #\u555f\u8070\u4e2d\u5fc3 #\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95 #\u8056\u8a95\u5feb\u6a02<\/p>\n\n\n\n<p>\u258e\u5831\u540d \u2022 \u67e5\u8a62 \u258e\u806f\u7e6b\uff1a\u4f55\u5148\u751f\/\u6881\u5c0f\u59d0<br>\ud83d\udccd\u89aa\u81e8\uff1a\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3<br>\ud83d\udccd\u96fb\u8a71\uff1a2826 1658<br>\ud83d\udccd\u77ed\u8a0a\uff1a6651 6093<br>\ud83d\udccd\u5fae\u4fe1\uff1aDCENTER2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf84\ud83d\udd14 \u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\u4eca\u5e74\u6d3b\u52d5\u5c07\u70ba\u5927\u5bb6\u5e36\u4f86\u7cbe\u5f69\u7684\u624b\u8a9e\u77ed\u5287\ud83c\udf85\u3001\u6709\u8da3\u6b61\u6a02\u7684\u805a\u6703\u904a\u6232 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":22430,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126,191,113],"tags":[],"class_list":["post-22429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association-news-mda","category-news-all","category-activity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f-2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\ud83c\udf84\ud83d\udd14 \u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\u4eca\u5e74\u6d3b\u52d5\u5c07\u70ba\u5927\u5bb6\u5e36\u4f86\u7cbe\u5f69\u7684\u624b\u8a9e\u77ed\u5287\ud83c\udf85\u3001\u6709\u8da3\u6b61\u6a02\u7684\u805a\u6703\u904a\u6232 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f-2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-21T03:53:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T08:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84\",\"datePublished\":\"2023-11-21T03:53:05+00:00\",\"dateModified\":\"2024-09-26T08:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\"},\"wordCount\":2,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg\",\"articleSection\":[\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u6240\u6709\u6d88\u606f\",\"\u6d3b\u52d5\"],\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\",\"name\":\"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg\",\"datePublished\":\"2023-11-21T03:53:05+00:00\",\"dateModified\":\"2024-09-26T08:10:02+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg\",\"width\":1131,\"height\":1600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f-2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/","og_locale":"zh_TW","og_type":"article","og_title":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\ud83c\udf84\ud83d\udd14 \u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\u4eca\u5e74\u6d3b\u52d5\u5c07\u70ba\u5927\u5bb6\u5e36\u4f86\u7cbe\u5f69\u7684\u624b\u8a9e\u77ed\u5287\ud83c\udf85\u3001\u6709\u8da3\u6b61\u6a02\u7684\u805a\u6703\u904a\u6232 [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f-2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2023-11-21T03:53:05+00:00","article_modified_time":"2024-09-26T08:10:02+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84","datePublished":"2023-11-21T03:53:05+00:00","dateModified":"2024-09-26T08:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/"},"wordCount":2,"commentCount":0,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg","articleSection":["\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u6240\u6709\u6d88\u606f","\u6d3b\u52d5"],"inLanguage":"zh-TW","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/","url":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/","name":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f 2023\u5171\u6e21\u7e7d\u7d1b\u8056\u8a95\u7bc0 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg","datePublished":"2023-11-21T03:53:05+00:00","dateModified":"2024-09-26T08:10:02+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f-2023%e5%85%b1%e6%b8%a1%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e7%af%80-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-21-at-11.45.54.jpeg","width":1131,"height":1600},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/22429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=22429"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/22429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/22430"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=22429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=22429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=22429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}