{"id":22613,"date":"2024-01-06T16:29:06","date_gmt":"2024-01-06T08:29:06","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=22613"},"modified":"2024-09-26T16:09:59","modified_gmt":"2024-09-26T08:09:59","slug":"%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/","title":{"rendered":"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image alignfull size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"464\" data-id=\"22623\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg\" alt=\"\" class=\"wp-image-22623\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM-768x445.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"22619\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM.jpeg\" alt=\"\" class=\"wp-image-22619\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM.jpeg 1600w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-800x600.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-768x576.jpeg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"22620\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-1.jpeg\" alt=\"\" class=\"wp-image-22620\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-1.jpeg 1600w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-1-800x600.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-1-768x576.jpeg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-1-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"22621\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM.jpeg\" alt=\"\" class=\"wp-image-22621\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM.jpeg 1600w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-800x600.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-768x576.jpeg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.10-PM-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"22617\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-1.jpeg\" alt=\"\" class=\"wp-image-22617\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-1.jpeg 1600w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-1-800x600.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-1-768x576.jpeg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-1-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"22622\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM-1.jpeg\" alt=\"\" class=\"wp-image-22622\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM-1.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM-1-768x576.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"22616\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM.jpeg\" alt=\"\" class=\"wp-image-22616\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM.jpeg 1600w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-800x600.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-768x576.jpeg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"22614\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-1.jpeg\" alt=\"\" class=\"wp-image-22614\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-1.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-1-768x576.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"22618\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-2.jpeg\" alt=\"\" class=\"wp-image-22618\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-2.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.12-PM-2-768x576.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"576\" data-id=\"22615\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-2.jpeg\" alt=\"\" class=\"wp-image-22615\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-2.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.11-PM-2-768x553.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u70ba\u4fc3\u9032\u5927\u7063\u5340\u807e\u4eba\u7fa4\u9ad4\u4e4b\u9593\u7684\u4ea4\u6d41\u8207\u5408\u4f5c\uff0c\u4ee5\u53ca\u52a0\u5f37\u7cb5\u6fb3\u807e\u4eba\u4e4b\u9593\u7684\u806f\u7e6b\uff0c\u672c\u6703\u7d44\u7e54\u4e86\u4e00\u9023\u5169\u65e5\u7684\u4ea4\u6d41\u6d3b\u52d5\uff0c\u524d\u5f80\u5ee3\u5dde\u62dc\u6703\u5ee3\u5dde\u807e\u4eba\u5354\u6703\u3002\u6d3b\u52d5\u4ee5\u201c\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u201d\u70ba\u4e3b\u984c\uff0c\u4e00\u4f86\u5be6\u5730\u9ad4\u9a57\u548c\u6df1\u5165\u4e86\u89e3\u5ee3\u5dde\u7121\u969c\u7919\u74b0\u5883\u5efa\u8a2d\uff0c\u4e8c\u4f86\u8b93\u7a57\u6fb3\u5169\u5730\u807e\u4eba\u53ca\u807d\u969c\u4eba\u58eb\u642d\u5efa\u4ea4\u6d41\u5e73\u53f0\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5728\u4ea4\u6d41\u904e\u7a0b\u4e2d\uff0c\u4e86\u89e3\u5230\u570b\u5167\u4f01\u696d\u70ba\u807e\u4eba\u53ca\u807d\u969c\u4eba\u58eb\u7814\u767c\u7684\u807d\u89ba\u7121\u969c\u7919\u79d1\u6280\u7522\u54c1\uff0c\u5982\u667a\u6167\u624b\u6a5f\u548c\u624b\u9336\u7684\u8a9e\u97f3\u6587\u5b57\u8f49\u63db\u6280\u8853\uff0c\u4ee5\u53ca\u773c\u93e1\u5b57\u5e55\u7b49\u3002\u9019\u4e9b\u6280\u8853\u7684\u61c9\u7528\u70ba\u807e\u4eba\u53ca\u807d\u969c\u4eba\u58eb\u63d0\u4f9b\u4e86\u66f4\u4fbf\u6377\u7684\u6e9d\u901a\u65b9\u5f0f\u3002\u6b64\u5916\uff0c\u5ee3\u5dde\u807e\u4eba\u5354\u6703\u9084\u5b89\u6392\u4e86\u624b\u8a9e\u5c0e\u89bd\u4eba\u54e1\u53c3\u89c0\u5357\u8d8a\u738b\u535a\u7269\u9662\uff0c\u901a\u904e\u7121\u969c\u7919\u5c0e\u89bd\u65b9\u5f0f\u4e86\u89e3\u5c55\u54c1\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u540c\u6642\uff0c\u7a57\u6fb3\u5169\u5730\u7684\u807e\u4eba\u53ca\u807d\u969c\u670b\u53cb\u4e5f\u5206\u4eab\u4e86\u7576\u5730\u7684\u807e\u4eba\u6559\u80b2\u3001\u5c31\u696d\u548c\u793e\u6703\u53c3\u8207\u4ee5\u53ca\u807e\u4eba\u670d\u52d9\u7684\u60c5\u6cc1\u3002\u4fc3\u9032\u4e86\u807e\u4eba\u7fa4\u9ad4\u4e4b\u9593\u7684\u4ea4\u6d41\u548c\u806f\u7e6b\uff0c\u589e\u9032\u4e86\u5f7c\u6b64\u7684\u4e86\u89e3\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#\u6fb3\u9580\u807e\u4eba\u5354\u6703 #\u5ee3\u5dde\u807e\u4eba\u5354\u6703<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u70ba\u4fc3\u9032\u5927\u7063\u5340\u807e\u4eba\u7fa4\u9ad4\u4e4b\u9593\u7684\u4ea4\u6d41\u8207\u5408\u4f5c\uff0c\u4ee5\u53ca\u52a0\u5f37\u7cb5\u6fb3\u807e\u4eba\u4e4b\u9593\u7684\u806f\u7e6b\uff0c\u672c\u6703\u7d44\u7e54\u4e86\u4e00\u9023\u5169\u65e5\u7684\u4ea4\u6d41\u6d3b\u52d5\uff0c\u524d\u5f80\u5ee3\u5dde\u62dc\u6703\u5ee3 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":22623,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,126,191],"tags":[],"class_list":["post-22613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association-news","category-association-news-mda","category-news-all"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u3010\u6e9d\u901a\u7121\u969c\u7919-\u5169\u57ce\u66f4\u6709\u611b\u3011-\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\u70ba\u4fc3\u9032\u5927\u7063\u5340\u807e\u4eba\u7fa4\u9ad4\u4e4b\u9593\u7684\u4ea4\u6d41\u8207\u5408\u4f5c\uff0c\u4ee5\u53ca\u52a0\u5f37\u7cb5\u6fb3\u807e\u4eba\u4e4b\u9593\u7684\u806f\u7e6b\uff0c\u672c\u6703\u7d44\u7e54\u4e86\u4e00\u9023\u5169\u65e5\u7684\u4ea4\u6d41\u6d3b\u52d5\uff0c\u524d\u5f80\u5ee3\u5dde\u62dc\u6703\u5ee3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u3010\u6e9d\u901a\u7121\u969c\u7919-\u5169\u57ce\u66f4\u6709\u611b\u3011-\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-06T08:29:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T08:09:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b\",\"datePublished\":\"2024-01-06T08:29:06+00:00\",\"dateModified\":\"2024-09-26T08:09:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg\",\"articleSection\":[\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u6240\u6709\u6d88\u606f\"],\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/\",\"name\":\"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg\",\"datePublished\":\"2024-01-06T08:29:06+00:00\",\"dateModified\":\"2024-09-26T08:09:59+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg\",\"width\":800,\"height\":464},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u3010\u6e9d\u901a\u7121\u969c\u7919-\u5169\u57ce\u66f4\u6709\u611b\u3011-\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\/","og_locale":"zh_TW","og_type":"article","og_title":"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\u70ba\u4fc3\u9032\u5927\u7063\u5340\u807e\u4eba\u7fa4\u9ad4\u4e4b\u9593\u7684\u4ea4\u6d41\u8207\u5408\u4f5c\uff0c\u4ee5\u53ca\u52a0\u5f37\u7cb5\u6fb3\u807e\u4eba\u4e4b\u9593\u7684\u806f\u7e6b\uff0c\u672c\u6703\u7d44\u7e54\u4e86\u4e00\u9023\u5169\u65e5\u7684\u4ea4\u6d41\u6d3b\u52d5\uff0c\u524d\u5f80\u5ee3\u5dde\u62dc\u6703\u5ee3 [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\u3010\u6e9d\u901a\u7121\u969c\u7919-\u5169\u57ce\u66f4\u6709\u611b\u3011-\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2024-01-06T08:29:06+00:00","article_modified_time":"2024-09-26T08:09:59+00:00","og_image":[{"width":800,"height":464,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"3 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b","datePublished":"2024-01-06T08:29:06+00:00","dateModified":"2024-09-26T08:09:59+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg","articleSection":["\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u6240\u6709\u6d88\u606f"],"inLanguage":"zh-TW","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/","url":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/","name":"\u3010\u6e9d\u901a\u7121\u969c\u7919 \u5169\u57ce\u66f4\u6709\u611b\u3011 #\u7a57\u6fb3\u807e\u5354\u7121\u969c\u7919\u4ea4\u6d41\u4fc3\u806f\u7e6b - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg","datePublished":"2024-01-06T08:29:06+00:00","dateModified":"2024-09-26T08:09:59+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e3%80%90%e6%ba%9d%e9%80%9a%e7%84%a1%e9%9a%9c%e7%a4%99-%e5%85%a9%e5%9f%8e%e6%9b%b4%e6%9c%89%e6%84%9b%e3%80%91-%e7%a9%97%e6%be%b3%e8%81%be%e5%8d%94%e7%84%a1%e9%9a%9c%e7%a4%99%e4%ba%a4%e6%b5%81\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-4.23.09-PM.jpeg","width":800,"height":464},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/22613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=22613"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/22613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/22623"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=22613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=22613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=22613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}