{"id":23050,"date":"2024-02-29T10:37:41","date_gmt":"2024-02-29T02:37:41","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=23050"},"modified":"2025-01-22T17:42:25","modified_gmt":"2025-01-22T09:42:25","slug":"%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/","title":{"rendered":"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1505\" height=\"2048\" src=\"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg?fit=800%2C1089&amp;ssl=1\" alt=\"\" class=\"wp-image-23051\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg 1505w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-588x800.jpg 588w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-768x1045.jpg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-1128x1536.jpg 1128w\" sizes=\"(max-width: 1505px) 100vw, 1505px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2048\" height=\"1390\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-02-2048x1390.jpg\" alt=\"\" class=\"wp-image-23052\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-02-scaled.jpg 2048w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-02-800x543.jpg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-02-768x521.jpg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-02-1536x1042.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":23051,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[241,119,126,191,225],"tags":[],"class_list":["post-23050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-241","category-association-news","category-association-news-mda","category-news-all","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a-2024\u5e743\u6708\u520a\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a-2024\u5e743\u6708\u520a\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T02:37:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T09:42:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1505\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a\",\"datePublished\":\"2024-02-29T02:37:41+00:00\",\"dateModified\":\"2025-01-22T09:42:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202403\u6708\u5feb\u8a0a-01-scaled.jpg\",\"articleSection\":[\"2024 \u5feb\u8a0a\",\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u6240\u6709\u6d88\u606f\",\"\u807e\u5354\u5feb\u8a0a\"],\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/\",\"name\":\"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202403\u6708\u5feb\u8a0a-01-scaled.jpg\",\"datePublished\":\"2024-02-29T02:37:41+00:00\",\"dateModified\":\"2025-01-22T09:42:25+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202403\u6708\u5feb\u8a0a-01-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202403\u6708\u5feb\u8a0a-01-scaled.jpg\",\"width\":1505,\"height\":2048},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a-2024\u5e743\u6708\u520a\/","og_locale":"zh_TW","og_type":"article","og_title":"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_url":"https:\/\/mda.org.mo\/home\/\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a-2024\u5e743\u6708\u520a\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2024-02-29T02:37:41+00:00","article_modified_time":"2025-01-22T09:42:25+00:00","og_image":[{"width":1505,"height":2048,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a","datePublished":"2024-02-29T02:37:41+00:00","dateModified":"2025-01-22T09:42:25+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg","articleSection":["2024 \u5feb\u8a0a","\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u6240\u6709\u6d88\u606f","\u807e\u5354\u5feb\u8a0a"],"inLanguage":"zh-TW","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/","url":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/","name":"\u807e\u5354\u6d3b\u52d5\u5feb\u8a0a \u2013 2024\u5e743\u6708\u520a - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg","datePublished":"2024-02-29T02:37:41+00:00","dateModified":"2025-01-22T09:42:25+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e8%81%be%e5%8d%94%e6%b4%bb%e5%8b%95%e5%bf%ab%e8%a8%8a-2024%e5%b9%b43%e6%9c%88%e5%88%8a\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2024\/02\/202403\u6708\u5feb\u8a0a-01-scaled.jpg","width":1505,"height":2048},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/23050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=23050"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/23050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/23051"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=23050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=23050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=23050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}