{"id":27029,"date":"2025-02-20T10:49:47","date_gmt":"2025-02-20T02:49:47","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=27029"},"modified":"2025-02-20T10:49:49","modified_gmt":"2025-02-20T02:49:49","slug":"%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/","title":{"rendered":"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55"},"content":{"rendered":"\n<p>\u3010 #\u6d3b\u52d5\u63a8\u85a6 \u3011<br>\u7531\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3\u53ca\u4e2d\u570b\u807e\u4eba\u5354\u6703\u8209\u8fa6\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55\ud83d\udcf8\u73fe\u6b63\u9032\u884c\u4f5c\u54c1\u5fb5\u96c6\ud83d\udce3\uff01<br>\ud83d\udd34 \u622a\u6b62\u6642\u9593\uff1a2025\u5e745\u67085\u65e5\uff08\u4ee5\u6536\u5230\u4f5c\u54c1\u6642\u9593\u70ba\u6e96)<br>\ud83d\udd34 \u6d3b\u52d5\u7ae0\u7a0b\uff1ahttps:\/\/zg.cpanet.cn\/activity\/ow37N83c9lqYYvn3<\/p>\n\n\n\n<p>\u6709\u8208\u8da3\u53c3\u52a0\u7684\u807e\u4eba\u6216\u807d\u969c\u670b\u53cb\uff0c\u806f\u7d61\u4e2d\u5fc3\u793e\u5de5\u6881\u59d1\u5a18\uff01<\/p>\n\n\n\n<p>\u258e\u67e5\u8a62 \u258e\u806f\u7e6b\uff1a\u6881\u59d1\u5a18<br>\ud83d\udccd\u89aa\u81e8\uff1a\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3<br>\ud83d\udccd\u96fb\u8a71\uff1a2826 1658<br>\ud83d\udccd\u77ed\u8a0a\uff1a6651 6093<br>\ud83d\udccd\u5fae\u4fe1\uff1aDCENTER2015<\/p>\n\n\n\n<p>#\u6fb3\u9580\u807e\u4eba\u5354\u6703 #\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3\u00a0#\u7043\u6a19\u676f\u00a0#\u95dc\u611b\u6b98\u969c\u00a0#\u651d\u5f71\u5c55\u00a0#\u5c55\u80fd\u85dd\u8853\ud83d\udcf8<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3010 #\u6d3b\u52d5\u63a8\u85a6 \u3011\u7531\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3\u53ca\u4e2d\u570b\u807e\u4eba\u5354\u6703\u8209\u8fa6\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":27030,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,126,112,191,113],"tags":[],"class_list":["post-27029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association-news","category-association-news-mda","category-related-activities","category-news-all","category-activity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u7b2c\u5341\u4e09\u5c46\u7043\u6a19\u676f\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u95dc\u611b\u6b98\u969c\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\u3010 #\u6d3b\u52d5\u63a8\u85a6 \u3011\u7531\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3\u53ca\u4e2d\u570b\u807e\u4eba\u5354\u6703\u8209\u8fa6\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u7b2c\u5341\u4e09\u5c46\u7043\u6a19\u676f\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u95dc\u611b\u6b98\u969c\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-20T02:49:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T02:49:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/02\/202412061146066315.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55\",\"datePublished\":\"2025-02-20T02:49:47+00:00\",\"dateModified\":\"2025-02-20T02:49:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/202412061146066315.jpg\",\"articleSection\":[\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u6240\u6709\u6d3b\u52d5\",\"\u6240\u6709\u6d88\u606f\",\"\u6d3b\u52d5\"],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/\",\"name\":\"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/202412061146066315.jpg\",\"datePublished\":\"2025-02-20T02:49:47+00:00\",\"dateModified\":\"2025-02-20T02:49:49+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/202412061146066315.jpg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/202412061146066315.jpg\",\"width\":1920,\"height\":600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u7b2c\u5341\u4e09\u5c46\u7043\u6a19\u676f\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u95dc\u611b\u6b98\u969c\/","og_locale":"zh_TW","og_type":"article","og_title":"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\u3010 #\u6d3b\u52d5\u63a8\u85a6 \u3011\u7531\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3\u53ca\u4e2d\u570b\u807e\u4eba\u5354\u6703\u8209\u8fa6\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\u7b2c\u5341\u4e09\u5c46\u7043\u6a19\u676f\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u95dc\u611b\u6b98\u969c\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2025-02-20T02:49:47+00:00","article_modified_time":"2025-02-20T02:49:49+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/02\/202412061146066315.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55","datePublished":"2025-02-20T02:49:47+00:00","dateModified":"2025-02-20T02:49:49+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/"},"wordCount":10,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/02\/202412061146066315.jpg","articleSection":["\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u6240\u6709\u6d3b\u52d5","\u6240\u6709\u6d88\u606f","\u6d3b\u52d5"],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/","url":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/","name":"\u7b2c\u5341\u4e09\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/02\/202412061146066315.jpg","datePublished":"2025-02-20T02:49:47+00:00","dateModified":"2025-02-20T02:49:49+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e7%ac%ac%e5%8d%81%e4%b8%89%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e5%9c%8b%e9%9a%9b%e8%81%bd%e9%9a%9c%e6%94%9d%e5%bd%b1%e5%b1%95%e6%9a%a8%e9%97%9c%e6%84%9b%e6%ae%98%e9%9a%9c\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/02\/202412061146066315.jpg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/02\/202412061146066315.jpg","width":1920,"height":600},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/27029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=27029"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/27029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/27030"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=27029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=27029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=27029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}