{"id":27847,"date":"2025-01-08T15:19:03","date_gmt":"2025-01-08T07:19:03","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=27847"},"modified":"2025-07-09T16:36:30","modified_gmt":"2025-07-09T08:36:30","slug":"%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/","title":{"rendered":"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.tdm.com.mo\/zh-hant\/video\/program-playlist\/506886?tabIndex=0\"><img fetchpriority=\"high\" decoding=\"async\" width=\"659\" height=\"363\" data-id=\"27855\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-18.png\" alt=\"\" class=\"wp-image-27855\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.tdm.com.mo\/zh-hant\/video\/program-playlist\/506886?tabIndex=0\">\u9032\u5165\u89c0\u770b<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566<\/p>\n","protected":false},"author":8,"featured_media":27855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[245,119,126,19,191],"tags":[],"class_list":["post-27847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-msl2025","category-association-news","category-association-news-mda","category-mind-sign-language","category-news-all"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-08T07:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T08:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-18.png\" \/>\n\t<meta property=\"og:image:width\" content=\"659\" \/>\n\t<meta property=\"og:image:height\" content=\"363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\",\"datePublished\":\"2025-01-08T07:19:03+00:00\",\"dateModified\":\"2025-07-09T08:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-18.png\",\"articleSection\":[\"2025 \u5fc3\u9748\u624b\u8a9e\",\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u5fc3\u9748\u624b\u8a9e\",\"\u6240\u6709\u6d88\u606f\"],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/\",\"name\":\"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-18.png\",\"datePublished\":\"2025-01-08T07:19:03+00:00\",\"dateModified\":\"2025-07-09T08:36:30+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-18.png\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-18.png\",\"width\":659,\"height\":363},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\/","og_locale":"zh_TW","og_type":"article","og_title":"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566","og_url":"https:\/\/mda.org.mo\/home\/\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2025-01-08T07:19:03+00:00","article_modified_time":"2025-07-09T08:36:30+00:00","og_image":[{"width":659,"height":363,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-18.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566","datePublished":"2025-01-08T07:19:03+00:00","dateModified":"2025-07-09T08:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/"},"wordCount":0,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-18.png","articleSection":["2025 \u5fc3\u9748\u624b\u8a9e","\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u5fc3\u9748\u624b\u8a9e","\u6240\u6709\u6d88\u606f"],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/","url":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/","name":"\u4eca\u65e5\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u6703\u7e7c\u7e8c\u8b1b\u5230\u725b\u8089\u4e7e\uff0c\u4e00\u9f4a\u5b78\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-18.png","datePublished":"2025-01-08T07:19:03+00:00","dateModified":"2025-07-09T08:36:30+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e6%97%a5%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e6%9c%83%e7%b9%bc%e7%ba%8c%e8%ac%9b%e5%88%b0%e7%89%9b%e8%82%89%e4%b9%be%ef%bc%8c%e4%b8%80%e9%bd%8a%e5%ad%b8%e4%b8%8b%e7%9b%b8\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-18.png","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-18.png","width":659,"height":363},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/27847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=27847"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/27847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/27855"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=27847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=27847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=27847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}