{"id":28185,"date":"2025-03-24T14:28:31","date_gmt":"2025-03-24T06:28:31","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=28185"},"modified":"2025-07-30T17:34:52","modified_gmt":"2025-07-30T09:34:52","slug":"%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/","title":{"rendered":"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b&#8221;\u7559\u6fb3\u6d88\u8cbb&#8221;\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.tdm.com.mo\/zh-hant\/video\/program-playlist\/514638?date=2025-03-17&amp;shortvideo=0&amp;isvideo\"><img fetchpriority=\"high\" decoding=\"async\" width=\"741\" height=\"419\" data-id=\"28125\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-64.png\" alt=\"\" class=\"wp-image-28125\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.tdm.com.mo\/zh-hant\/video\/program-playlist\/514638?date=2025-03-17&amp;shortvideo=0&amp;isvideo\">\u9032\u5165\u89c0\u770b<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":28125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[245,119,126,19,191],"tags":[],"class_list":["post-28185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-msl2025","category-association-news","category-association-news-mda","category-mind-sign-language","category-news-all"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b&quot;\u7559\u6fb3\u6d88\u8cbb&quot;\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\u7559\u6fb3\u6d88\u8cbb\uff0c\u4e00\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b&quot;\u7559\u6fb3\u6d88\u8cbb&quot;\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\u7559\u6fb3\u6d88\u8cbb\uff0c\u4e00\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-24T06:28:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T09:34:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-64.png\" \/>\n\t<meta property=\"og:image:width\" content=\"741\" \/>\n\t<meta property=\"og:image:height\" content=\"419\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b&#8221;\u7559\u6fb3\u6d88\u8cbb&#8221;\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002\",\"datePublished\":\"2025-03-24T06:28:31+00:00\",\"dateModified\":\"2025-07-30T09:34:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-64.png\",\"articleSection\":[\"2025 \u5fc3\u9748\u624b\u8a9e\",\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u5fc3\u9748\u624b\u8a9e\",\"\u6240\u6709\u6d88\u606f\"],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/\",\"name\":\"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\\\"\u7559\u6fb3\u6d88\u8cbb\\\"\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-64.png\",\"datePublished\":\"2025-03-24T06:28:31+00:00\",\"dateModified\":\"2025-07-30T09:34:52+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-64.png\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image-64.png\",\"width\":741,\"height\":419},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\"\u7559\u6fb3\u6d88\u8cbb\"\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\u7559\u6fb3\u6d88\u8cbb\uff0c\u4e00\/","og_locale":"zh_TW","og_type":"article","og_title":"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\"\u7559\u6fb3\u6d88\u8cbb\"\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_url":"https:\/\/mda.org.mo\/home\/\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\u7559\u6fb3\u6d88\u8cbb\uff0c\u4e00\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2025-03-24T06:28:31+00:00","article_modified_time":"2025-07-30T09:34:52+00:00","og_image":[{"width":741,"height":419,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-64.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b&#8221;\u7559\u6fb3\u6d88\u8cbb&#8221;\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002","datePublished":"2025-03-24T06:28:31+00:00","dateModified":"2025-07-30T09:34:52+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/"},"wordCount":0,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-64.png","articleSection":["2025 \u5fc3\u9748\u624b\u8a9e","\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u5fc3\u9748\u624b\u8a9e","\u6240\u6709\u6d88\u606f"],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/","url":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/","name":"\u4eca\u500b\u661f\u671f\u300a\u5fc3\u9748\u624b\u8a9e\u300b\u5605\u4e3b\u984c\u4fc2\u8b1b\"\u7559\u6fb3\u6d88\u8cbb\"\uff0c\u4e00\u9f4a\u7747\u4e0b\u76f8\u95dc\u5605\u624b\u8a9e\u5566\u3002 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-64.png","datePublished":"2025-03-24T06:28:31+00:00","dateModified":"2025-07-30T09:34:52+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e4%bb%8a%e5%80%8b%e6%98%9f%e6%9c%9f%e3%80%8a%e5%bf%83%e9%9d%88%e6%89%8b%e8%aa%9e%e3%80%8b%e5%98%85%e4%b8%bb%e9%a1%8c%e4%bf%82%e8%ac%9b%e7%95%99%e6%be%b3%e6%b6%88%e8%b2%bb%ef%bc%8c%e4%b8%80\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-64.png","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/07\/image-64.png","width":741,"height":419},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/28185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=28185"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/28185\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/28125"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=28185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=28185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=28185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}