{"id":28840,"date":"2025-11-17T18:11:35","date_gmt":"2025-11-17T10:11:35","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=28840"},"modified":"2025-11-17T18:12:13","modified_gmt":"2025-11-17T10:12:13","slug":"%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/","title":{"rendered":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1448\" height=\"2048\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06-1448x2048.jpg\" alt=\"\" class=\"wp-image-28841\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06-1448x2048.jpg 1448w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06-566x800.jpg 566w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06-768x1086.jpg 768w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06-1086x1536.jpg 1086w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06.jpg 1810w\" sizes=\"(max-width: 1448px) 100vw, 1448px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\ud83d\ude4c\ud83c\udffb<br>\u4eca\u5e74\u9664\u4e86\u7e7c\u7e8c\u70ba\u5927\u5bb6\u5e36\u4f86\u8c50\u5bcc\u7684\u7f8e\u98df\u4f73\u991a\u53ca\u62bd\u734e\u74b0\u7bc0\u5916\ud83c\udf81\uff01\u6d3b\u52d5\u66f4\u878d\u5165\u4e86\u9ad4\u80b2\u904b\u52d5\u5143\u7d20\u4e92\u52d5\u904a\u6232\ud83c\udfae\uff0c\u4ee5\u97ff\u61c9\u5168\u570b\u7b2c\u5341\u4e8c\u5c46\u6b98\u75be\u4eba\u904b\u52d5\u6703\u3002<br>\u671f\u5f85\u60a8\u7684\u53c3\u8207\uff0c\u8b93\u6211\u5011\u5171\u805a\u4e00\u5802\uff0c\u5ea6\u904e\u6eab\u99a8\u7684\u8056\u8a95\u6642\u5149\uff01\ud83d\udc6a\ud83d\udc95<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u65e5\u671f\uff1a2025\u5e7412\u670814\u65e5(\u661f\u671f\u65e5)<br>\u6642\u9593\uff1a12:00 \u2013 14:30 (11:30\u958b\u59cb\u5165\u5834)<br>\u5730\u9ede\uff1a\u5bcc\u8c6a\u6d77\u9bae\u9152\u5bb6-\u5bcc\u8c6a\u5ef3<br>\u5c0d\u8c61\uff1a\u807e\/\u807d\u969c\u670d\u52d9\u5c0d\u8c61\u53ca\u5176\u5bb6\u5c6c<br>\u5167\u5bb9\uff1a\u4e2d\u5f0f\u5348\u9910\u3001\u904a\u6232\u53ca\u5927\u62bd\u734e<br>\u8cbb\u7528\uff1a\u8a73\u60c5\u8acb\u898b\u6d77\u5831<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udce2\u5831\u540d\u9808\u77e5\uff1a<br>\u2022\u2060 \u2060\u5831\u540d\u75312025\u5e7411\u670818\u65e5\u81f311\u670829\u65e5\u6b62\u3002<br>\u2022\u2060 \u2060\u5831\u540d\u9700\u5e36\u540c\u8eab\u4efd\u8b49\u3001\u670d\u52d9\u5c0d\u8c61\u8a3c\/\u6703\u54e1\u8b49\u89aa\u81e8\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3\u7e73\u8cbb\uff0c\u7e73\u8cbb\u5f8c\u4e0d\u8a2d\u9000\u6b3e\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u258e\u5831\u540d \u2022 \u67e5\u8a62 \u258e\u970d\u5c0f\u59d0\/\u99ae\u5148\u751f<br>\ud83d\udccd\u89aa\u81e8\uff1a\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3<br>\ud83d\udccd\u96fb\u8a71\uff1a2826 1658<br>\ud83d\udccd\u77ed\u8a0a\uff1a6651 6093<br>\ud83d\udccd\u5fae\u4fe1\uff1aDCENTER2015<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#\u6fb3\u9580\u807e\u4eba\u5354\u6703 #\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3 #\u555f\u8070\u4e2d\u5fc3 #\u7e7d\u7d1b\u8056\u8a95\u807e\u805a\u6d3b\u529b\u806f\u6b61\u6703 #\u8056\u8a95\u5feb\u6a02\ud83c\udf84<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\ud83d\ude4c\ud83c\udffb\u4eca\u5e74\u9664\u4e86\u7e7c\u7e8c\u70ba\u5927\u5bb6\u5e36\u4f86\u8c50\u5bcc\u7684\u7f8e\u98df\u4f73\u991a\u53ca\u62bd\u734e\u74b0\u7bc0\u5916\ud83c\udf81\uff01\u6d3b\u52d5\u66f4 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":28841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,126,112,191,113],"tags":[],"class_list":["post-28840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association-news","category-association-news-mda","category-related-activities","category-news-all","category-activity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\ud83d\ude4c\ud83c\udffb\u4eca\u5e74\u9664\u4e86\u7e7c\u7e8c\u70ba\u5927\u5bb6\u5e36\u4f86\u8c50\u5bcc\u7684\u7f8e\u98df\u4f73\u991a\u53ca\u62bd\u734e\u74b0\u7bc0\u5916\ud83c\udf81\uff01\u6d3b\u52d5\u66f4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T10:11:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T10:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84\",\"datePublished\":\"2025-11-17T10:11:35+00:00\",\"dateModified\":\"2025-11-17T10:12:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\"},\"wordCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/PHOTO-2025-11-17-18-07-06.jpg\",\"articleSection\":[\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u6240\u6709\u6d3b\u52d5\",\"\u6240\u6709\u6d88\u606f\",\"\u6d3b\u52d5\"],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\",\"name\":\"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/PHOTO-2025-11-17-18-07-06.jpg\",\"datePublished\":\"2025-11-17T10:11:35+00:00\",\"dateModified\":\"2025-11-17T10:12:13+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/PHOTO-2025-11-17-18-07-06.jpg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/PHOTO-2025-11-17-18-07-06.jpg\",\"width\":1810,\"height\":2560},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/","og_locale":"zh_TW","og_type":"article","og_title":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\u5e74\u672b\u5c07\u81f3\uff0c\u4e00\u5834\u6eab\u99a8\u53c8\u5145\u6eff\u6b61\u6a02\u7684\u8056\u8a95\u805a\u9910\u53c8\u4f86\u81e8\u4e86\uff01\ud83d\ude4c\ud83c\udffb\u4eca\u5e74\u9664\u4e86\u7e7c\u7e8c\u70ba\u5927\u5bb6\u5e36\u4f86\u8c50\u5bcc\u7684\u7f8e\u98df\u4f73\u991a\u53ca\u62bd\u734e\u74b0\u7bc0\u5916\ud83c\udf81\uff01\u6d3b\u52d5\u66f4 [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703-\ud83e\udd1f\ud83c\udf89\ud83c\udf84\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2025-11-17T10:11:35+00:00","article_modified_time":"2025-11-17T10:12:13+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84","datePublished":"2025-11-17T10:11:35+00:00","dateModified":"2025-11-17T10:12:13+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/"},"wordCount":2,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06.jpg","articleSection":["\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u6240\u6709\u6d3b\u52d5","\u6240\u6709\u6d88\u606f","\u6d3b\u52d5"],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/","url":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/","name":"\ud83c\udf84\ud83c\udf89\ud83e\udd1f\u300a\u7e7d\u7d1b\u8056\u8a95\u30fb\u807e\u805a\u6d3b\u529b\u300b\u806f\u6b61\u6703 \ud83e\udd1f\ud83c\udf89\ud83c\udf84 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06.jpg","datePublished":"2025-11-17T10:11:35+00:00","dateModified":"2025-11-17T10:12:13+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%f0%9f%8e%84%f0%9f%8e%89%f0%9f%a4%9f%e3%80%8a%e7%b9%bd%e7%b4%9b%e8%81%96%e8%aa%95%e3%83%bb%e8%81%be%e8%81%9a%e6%b4%bb%e5%8a%9b%e3%80%8b%e8%81%af%e6%ad%a1%e6%9c%83-%f0%9f%a4%9f%f0%9f%8e%89%f0%9f%8e%84\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06.jpg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2025\/11\/PHOTO-2025-11-17-18-07-06.jpg","width":1810,"height":2560},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/28840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=28840"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/28840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/28841"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=28840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=28840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=28840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}