{"id":29397,"date":"2026-04-02T18:00:00","date_gmt":"2026-04-02T10:00:00","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=29397"},"modified":"2026-04-14T11:59:13","modified_gmt":"2026-04-14T03:59:13","slug":"%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/","title":{"rendered":"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"383\" src=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg\" alt=\"\" class=\"wp-image-29399\" srcset=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg 900w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM-800x340.jpeg 800w, https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM-768x327.jpeg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u7531 #\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3 \u53ca #\u4e2d\u570b\u807e\u4eba\u5354\u6703 \u8209\u8fa6\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71\u5c55\ud83d\udcf8\u73fe\u6b63\u9032\u884c\u4f5c\u54c1\u5fb5\u96c6\uff01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf9e\ufe0f \u6d3b\u52d5\u7ae0\u7a0b\u53ca\u5fb5\u7a3f\u7d30\u5247\uff0c\u8acb\u700f\u89bd\u4ee5\u4e0b\u7db2\u7ad9\uff1ahttps:\/\/zg.cpanet.cn\/activity\/AKSKWCbqHNLb62us<br>\ud83c\udf9e\ufe0f \u622a\u7a3f\u6642\u9593\uff1a2026\u5e745\u67085\u65e5\uff08\u4ee5\u6536\u5230\u4f5c\u54c1\u6642\u9593\u70ba\u6e96)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udce3 \u5c0d\u651d\u5f71\u6709\u8208\u8da3\u7684\u807e\u4eba\u6216\u807d\u969c\u670b\u53cb\uff0c\u8acb\u8e34\u8e8d\u4ea4\u51fa\u4f60\u7684\u4f5c\u54c1\u5427\uff01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u258e\u67e5\u8a62 \u258e\u806f\u7e6b\uff1a\u970d\u59d1\u5a18<br>\ud83d\udccd\u89aa\u81e8\uff1a\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3<br>\ud83d\udccd\u96fb\u8a71\uff1a2826 1658<br>\ud83d\udccd\u77ed\u8a0a\uff1a6651 6093<br>\ud83d\udccd\u5fae\u4fe1\uff1aDCENTER2015<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#\u6fb3\u9580\u807e\u4eba\u5354\u6703 #\u807e\u4eba\u670d\u52d9\u4e2d\u5fc3 #\u7043\u6a19\u676f #\u95dc\u611b\u6b98\u969c #\u651d\u5f71\u5c55 #\u5c55\u80fd\u85dd\u8853\ud83d\udcf8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u7531 #\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3 \u53ca #\u4e2d\u570b\u807e\u4eba\u5354\u6703 \u8209\u8fa6\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":29399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,126,112,191,113],"tags":[],"class_list":["post-29397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association-news","category-association-news-mda","category-related-activities","category-news-all","category-activity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u6d3b\u52d5\u63a8\u85a6-\uff5c\u3010\u7b2c\u5341\u56db\u5c46\u7043\u6a19\u676f\u651d\u5f71\u5c55-\u958b\u59cb\u63a5\u53d7\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\u7531 #\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3 \u53ca #\u4e2d\u570b\u807e\u4eba\u5354\u6703 \u8209\u8fa6\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u6d3b\u52d5\u63a8\u85a6-\uff5c\u3010\u7b2c\u5341\u56db\u5c46\u7043\u6a19\u676f\u651d\u5f71\u5c55-\u958b\u59cb\u63a5\u53d7\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T03:59:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"383\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\"},\"headline\":\"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7\",\"datePublished\":\"2026-04-02T10:00:00+00:00\",\"dateModified\":\"2026-04-14T03:59:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg\",\"articleSection\":[\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u6240\u6709\u6d3b\u52d5\",\"\u6240\u6709\u6d88\u606f\",\"\u6d3b\u52d5\"],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/\",\"name\":\"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg\",\"datePublished\":\"2026-04-02T10:00:00+00:00\",\"dateModified\":\"2026-04-14T03:59:13+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg\",\"width\":900,\"height\":383},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/81e5833e562e153bf81dd7ee72bc4845\",\"name\":\"Admin\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u6d3b\u52d5\u63a8\u85a6-\uff5c\u3010\u7b2c\u5341\u56db\u5c46\u7043\u6a19\u676f\u651d\u5f71\u5c55-\u958b\u59cb\u63a5\u53d7\/","og_locale":"zh_TW","og_type":"article","og_title":"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\u7531 #\u4e2d\u570b\u6587\u806f\u651d\u5f71\u85dd\u8853\u4e2d\u5fc3 \u53ca #\u4e2d\u570b\u807e\u4eba\u5354\u6703 \u8209\u8fa6\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u570b\u969b\u807d\u969c\u651d\u5f71\u5c55\u66a8\u201c\u95dc\u611b\u6b98\u969c\u201d\u4e3b\u984c\u516c\u76ca\u651d\u5f71 [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\u6d3b\u52d5\u63a8\u85a6-\uff5c\u3010\u7b2c\u5341\u56db\u5c46\u7043\u6a19\u676f\u651d\u5f71\u5c55-\u958b\u59cb\u63a5\u53d7\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2026-04-02T10:00:00+00:00","article_modified_time":"2026-04-14T03:59:13+00:00","og_image":[{"width":900,"height":383,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"Admin","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/"},"author":{"name":"Admin","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845"},"headline":"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7","datePublished":"2026-04-02T10:00:00+00:00","dateModified":"2026-04-14T03:59:13+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/"},"wordCount":8,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg","articleSection":["\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u6240\u6709\u6d3b\u52d5","\u6240\u6709\u6d88\u606f","\u6d3b\u52d5"],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/","url":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/","name":"\u6d3b\u52d5\u63a8\u85a6 \uff5c\u3010\u7b2c\u5341\u56db\u5c46\u201c\u7043\u6a19\u676f\u201d\u651d\u5f71\u5c55 \u958b\u59cb\u63a5\u53d7\u6295\u7a3f\u3011\ud83d\udcf7 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg","datePublished":"2026-04-02T10:00:00+00:00","dateModified":"2026-04-14T03:59:13+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e6%b4%bb%e5%8b%95%e6%8e%a8%e8%96%a6-%ef%bd%9c%e3%80%90%e7%ac%ac%e5%8d%81%e5%9b%9b%e5%b1%86%e7%81%83%e6%a8%99%e6%9d%af%e6%94%9d%e5%bd%b1%e5%b1%95-%e9%96%8b%e5%a7%8b%e6%8e%a5%e5%8f%97\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-5.55.15-PM.jpeg","width":900,"height":383},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/81e5833e562e153bf81dd7ee72bc4845","name":"Admin","url":"https:\/\/mda.org.mo\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/29397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=29397"}],"version-history":[{"count":0,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/29397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/29399"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=29397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=29397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=29397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}