{"id":29668,"date":"2026-04-20T18:00:00","date_gmt":"2026-04-20T10:00:00","guid":{"rendered":"https:\/\/mda.org.mo\/home\/?p=29668"},"modified":"2026-04-20T18:05:03","modified_gmt":"2026-04-20T10:05:03","slug":"%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3","status":"publish","type":"post","link":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/","title":{"rendered":"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f...\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/hxzbkmuO55w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udce2\u3010 #\u661f\u671f\u4e00\u624b\u8a9e\u3011<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#\u6fb3\u9580\u807e\u4eba\u5354\u6703 \u2715 #\u6fb3\u9580\u624b\u8a9e\u5354\u6703<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4eca\u500b\u661f\u671f\uff0c\u624b\u8a9e\u4e3b\u6301\u300c #\u53ef\u6b23\u300d\ud83d\udc67\ud83c\udffb\u300c #\u9cf4\u9cf4\u300d\ud83d\udc66\ud83c\udffb\u4ecb\u7d39\u300c #\u7e6a\u756b\uff0c \u90a3\u9ebc\u300c\u7e6a\u756b\u300d\u6fb3\u9580\u624b\u8a9e\u61c9\u8a72\u600e\u6a23\u8868\u9054\u5462\uff1f\u8acb\u9ede\u64ca\u5f71\u7247\u4e26\u7559\u610f\u6211\u5011\u7684\u300e\u661f\u671f\u4e00\u624b\u8a9e\u300f\u5566\uff01<br>\u2764\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011\u9022\u661f\u671f\u4e00\u63d0\u4f9b #\u4e0d\u540c\u5143\u7d20\u7684\u624b\u8a9e\u6559\u5b78 \uff0c\u8b93\u5927\u5bb6\u6709\u66f4\u591a\u6e20\u9053\u5b78\u7fd2\u53ca\u8a8d\u8b58\u300c #\u6fb3\u9580\u624b\u8a9e\u300d\uff0c\u656c\u8acb\u6536\u770b\u5566\uff01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#\u6fb3\u9580\u807e\u4eba\u5354\u6703 #\u6fb3\u9580\u624b\u8a9e\u5354\u6703 #\u661f\u671f\u4e00\u624b\u8a9e #\u8df3\u821e<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udce2\u3010 #\u661f\u671f\u4e00\u624b\u8a9e\u3011 #\u6fb3\u9580\u807e\u4eba\u5354\u6703 \u2715 #\u6fb3\u9580\u624b\u8a9e\u5354\u6703 \u4eca\u500b\u661f\u671f\uff0c\u624b\u8a9e\u4e3b\u6301\u300c #\u53ef\u6b23\u300d\ud83d\udc67\ud83c\udffb\u300c #\u9cf4\u9cf4\u300d\ud83d\udc66\ud83c\udffb\u4ecb [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":29669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[249,119,126,191,216],"tags":[],"class_list":["post-29668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-249","category-association-news","category-association-news-mda","category-news-all","category-216"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011 - \u6fb3\u9580\u807e\u4eba\u5354\u6703<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mda.org.mo\/home\/\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udce2\u3010 #\u661f\u671f\u4e00\u624b\u8a9e\u3011 #\u6fb3\u9580\u807e\u4eba\u5354\u6703 \u2715 #\u6fb3\u9580\u624b\u8a9e\u5354\u6703 \u4eca\u500b\u661f\u671f\uff0c\u624b\u8a9e\u4e3b\u6301\u300c #\u53ef\u6b23\u300d\ud83d\udc67\ud83c\udffb\u300c #\u9cf4\u9cf4\u300d\ud83d\udc66\ud83c\udffb\u4ecb [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mda.org.mo\/home\/\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacauDeafAssociation\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T10:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MDA EP Officer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005:\" \/>\n\t<meta name=\"twitter:data1\" content=\"MDA EP Officer\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/\"},\"author\":{\"name\":\"MDA EP Officer\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/c6aba0831078ebd8422438e1f71daa6a\"},\"headline\":\"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011\",\"datePublished\":\"2026-04-20T10:00:00+00:00\",\"dateModified\":\"2026-04-20T10:05:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg\",\"articleSection\":[\"2026\u5e74\u661f\u671f\u4e00\u624b\u8a9e\",\"\u5354\u6703\u65b0\u8a0a\",\"\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)\",\"\u6240\u6709\u6d88\u606f\",\"\u661f\u671f\u4e00\u624b\u8a9e\u3010\u6fb3\u9580\u807e\u4eba\u5354\u6703 \u2715 \u6fb3\u9580\u624b\u8a9e\u5354\u6703\u3011\"],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/\",\"name\":\"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011 - \u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg\",\"datePublished\":\"2026-04-20T10:00:00+00:00\",\"dateModified\":\"2026-04-20T10:05:03+00:00\",\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg\",\"contentUrl\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"description\":\"Macau Deaf Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#organization\",\"name\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mda.org.mo\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1\",\"width\":301,\"height\":72,\"caption\":\"\u6fb3\u9580\u807e\u4eba\u5354\u6703\"},\"image\":{\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacauDeafAssociation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/#\\\/schema\\\/person\\\/c6aba0831078ebd8422438e1f71daa6a\",\"name\":\"MDA EP Officer\",\"url\":\"https:\\\/\\\/mda.org.mo\\\/home\\\/author\\\/epofficer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mda.org.mo\/home\/\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\/","og_locale":"zh_TW","og_type":"article","og_title":"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","og_description":"\ud83d\udce2\u3010 #\u661f\u671f\u4e00\u624b\u8a9e\u3011 #\u6fb3\u9580\u807e\u4eba\u5354\u6703 \u2715 #\u6fb3\u9580\u624b\u8a9e\u5354\u6703 \u4eca\u500b\u661f\u671f\uff0c\u624b\u8a9e\u4e3b\u6301\u300c #\u53ef\u6b23\u300d\ud83d\udc67\ud83c\udffb\u300c #\u9cf4\u9cf4\u300d\ud83d\udc66\ud83c\udffb\u4ecb [&hellip;]","og_url":"https:\/\/mda.org.mo\/home\/\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\/","og_site_name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","article_publisher":"https:\/\/www.facebook.com\/MacauDeafAssociation","article_published_time":"2026-04-20T10:00:00+00:00","article_modified_time":"2026-04-20T10:05:03+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg","type":"image\/jpeg"}],"author":"MDA EP Officer","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005:":"MDA EP Officer","\u9810\u4f30\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/#article","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/"},"author":{"name":"MDA EP Officer","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/c6aba0831078ebd8422438e1f71daa6a"},"headline":"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011","datePublished":"2026-04-20T10:00:00+00:00","dateModified":"2026-04-20T10:05:03+00:00","mainEntityOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/"},"wordCount":5,"publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg","articleSection":["2026\u5e74\u661f\u671f\u4e00\u624b\u8a9e","\u5354\u6703\u65b0\u8a0a","\u5354\u6703\u65b0\u8a0a (\u6fb3\u9580\u807e\u4eba\u5354\u6703)","\u6240\u6709\u6d88\u606f","\u661f\u671f\u4e00\u624b\u8a9e\u3010\u6fb3\u9580\u807e\u4eba\u5354\u6703 \u2715 \u6fb3\u9580\u624b\u8a9e\u5354\u6703\u3011"],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/","url":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/","name":"\u8ddf\u8457\u7bc0\u594f\u81ea\u7531\u5f8b\u52d5\uff0c\u628a\u5fc3\u60c5\u8df3\u51fa\u4f86\uff0c\u4eab\u53d7\u7576\u4e0b\u3002\u60f3\u77e5\u9053\u300c\u8df3\u821e\u300d\u7684\u6fb3\u9580\u624b\u8a9e\u600e\u9ebc\u8868\u9054\u55ce\uff1f\u2026\u3010\u661f\u671f\u4e00\u624b\u8a9e\u3011 - \u6fb3\u9580\u807e\u4eba\u5354\u6703","isPartOf":{"@id":"https:\/\/mda.org.mo\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/#primaryimage"},"image":{"@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg","datePublished":"2026-04-20T10:00:00+00:00","dateModified":"2026-04-20T10:05:03+00:00","inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/%e8%b7%9f%e8%91%97%e7%af%80%e5%a5%8f%e8%87%aa%e7%94%b1%e5%be%8b%e5%8b%95%ef%bc%8c%e6%8a%8a%e5%bf%83%e6%83%85%e8%b7%b3%e5%87%ba%e4%be%86%ef%bc%8c%e4%ba%ab%e5%8f%97%e7%95%b6%e4%b8%8b%e3%80%82%e6%83%b3\/#primaryimage","url":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg","contentUrl":"https:\/\/mda.org.mo\/home\/wp-content\/uploads\/2026\/04\/\u661f\u671f\u4e00\u624b\u8a9e-\u8df3\u821e.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/mda.org.mo\/home\/#website","url":"https:\/\/mda.org.mo\/home\/","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","description":"Macau Deaf Association","publisher":{"@id":"https:\/\/mda.org.mo\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mda.org.mo\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/mda.org.mo\/home\/#organization","name":"\u6fb3\u9580\u807e\u4eba\u5354\u6703","url":"https:\/\/mda.org.mo\/home\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mda.org.mo\/home\/wp-content\/uploads\/2020\/03\/MDA-LOGO-Outline.png?fit=301%2C72&ssl=1","width":301,"height":72,"caption":"\u6fb3\u9580\u807e\u4eba\u5354\u6703"},"image":{"@id":"https:\/\/mda.org.mo\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacauDeafAssociation"]},{"@type":"Person","@id":"https:\/\/mda.org.mo\/home\/#\/schema\/person\/c6aba0831078ebd8422438e1f71daa6a","name":"MDA EP Officer","url":"https:\/\/mda.org.mo\/home\/author\/epofficer\/"}]}},"_links":{"self":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/29668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/comments?post=29668"}],"version-history":[{"count":2,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/29668\/revisions"}],"predecessor-version":[{"id":29672,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/posts\/29668\/revisions\/29672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media\/29669"}],"wp:attachment":[{"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/media?parent=29668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/categories?post=29668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mda.org.mo\/home\/wp-json\/wp\/v2\/tags?post=29668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}